{"id":389,"count":0,"description":"","link":"https:\/\/czechtravellers.com\/nl\/reizen-met-kinderen\/","name":"Reizen met kinderen","slug":"reizen-met-kinderen","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/czechtravellers.com\/nl\/wp-json\/wp\/v2\/categories\/389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/czechtravellers.com\/nl\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/czechtravellers.com\/nl\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/czechtravellers.com\/nl\/wp-json\/wp\/v2\/posts?categories=389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}